{"id":439,"date":"2020-11-24T13:11:34","date_gmt":"2020-11-24T12:11:34","guid":{"rendered":"http:\/\/www.nordisk-buero.com\/?p=439"},"modified":"2022-11-17T19:38:27","modified_gmt":"2022-11-17T18:38:27","slug":"praktikum-grafikdesign","status":"publish","type":"post","link":"https:\/\/nordisk-buero.com\/en\/praktikum-grafikdesign\/","title":{"rendered":"Praktikum Grafikdesign"},"content":{"rendered":"<p>Views: 19821<\/p>","protected":false},"excerpt":{"rendered":"<p>Views: 19821<\/p>\n","protected":false},"author":1,"featured_media":1543,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[23,24],"tags":[26],"class_list":["post-439","post","type-post","status-publish","has-post-thumbnail","hentry","category-jobs","category-frankfurt","tag-frankfurt"],"grid":"{\r\n  \"colCount\": 22,\r\n  \"colGutter\": 20,\r\n  \"rowGutters\": [],\r\n  \"frameMargin\": 5,\r\n  \"leftFrameMargin\": 20,\r\n  \"rightFrameMargin\": 20,\r\n  \"topFrameMargin\": 100,\r\n  \"bottomFrameMargin\": 100,\r\n  \"rowAttrs\": [\r\n    {\r\n      \"relid\": 6\r\n    }\r\n  ],\r\n  \"bgColor\": null,\r\n  \"cont\": [\r\n    {\r\n      \"type\": \"text\",\r\n      \"cont\": \"<h2 class=\\\"_Headline_H2\\\">Praktikum Grafikdesign Frankfurt<\/h2>\",\r\n      \"align\": \"top\",\r\n      \"row\": 0,\r\n      \"col\": 3,\r\n      \"colspan\": 7,\r\n      \"offsetx\": 0,\r\n      \"offsety\": 0,\r\n      \"spaceabove\": 0,\r\n      \"spacebelow\": 0,\r\n      \"yvel\": 1,\r\n      \"push\": 3,\r\n      \"relid\": 5,\r\n      \"absolute_position\": false\r\n    },\r\n    {\r\n      \"type\": \"text\",\r\n      \"cont\": \"<h2 class=\\\"_Jobs_Dreiklang\\\">Motiviert?<br \/>Aufgeschlossen?<br \/>Voller Ideen?<\/h2><h2 class=\\\"_Jobs_Dreiklang\\\">Klingt gut.<\/h2><p>\u00a0<\/p><p>Seit 1996 arbeiten wir in vielen Branchen und betreuen die unterschiedlichsten Kunden, f\u00fcr deren Design wir jemand wie Dich suchen. Als Praktikant*in wirst du f\u00fcr mindestens 6 Monate Teil unseres Kreations-Teams.<\/p><p class=\\\"_Headline_H3\\\">Es geht um<\/p><p class=\\\"_Liste\\\">Konzeption, Gestaltung und Umsetzung von Kommunikationskonzepten, Markenauftritten und Kampagnen \u2013 on- wie offline<\/p><p class=\\\"_Liste\\\">Kreative Unterst\u00fctzung bei der Gestaltung von Projekten<\/p><p class=\\\"_Liste\\\">\u00dcbernahme eigener Projekte (ganz ohne Kaffeekochen oder Kopieren!)<\/p><p class=\\\"_Headline_H3\\\">Du bringst mit<\/p><p class=\\\"_Liste\\\">Mindestens 4 Semester Erfahrung in Grafikdesign, Kommunikationsdesign, Medienmanagement oder einem vergleichbaren Studiengang<\/p><p class=\\\"_Liste\\\">Kenntnisse in den g\u00e4ngigen Grafikdesign Programmen<\/p><p class=\\\"_Liste\\\">Konzeptionelles und kreatives Denken<\/p><p class=\\\"_Liste\\\">Herzblut f\u00fcr Grafik und Design<\/p><p class=\\\"_Liste\\\">Teamgeist<\/p><p class=\\\"_Headline_H3\\\">Wir bieten dir<\/p><p class=\\\"_Liste\\\">Faire Arbeitszeiten und gute Konditionen<\/p><p class=\\\"_Liste\\\">Eine perfekte Lage direkt gegen\u00fcber vom Frankfurter Hauptbahnhof<\/p><p class=\\\"_Liste\\\">Eine sch\u00f6ne Agentur in einem klassischen Altbau mit gr\u00fcnem Dachgarten<\/p><p class=\\\"_Liste\\\">Kaffee aus einer italienischen Siebtr\u00e4germaschine<\/p><p class=\\\"_Liste\\\">verdammt nette Kolleginnen und Kollegen<\/p><p>\u00a0<\/p><p class=\\\"_Default\\\">Bitte schicke uns deine aussagekr\u00e4ftige Bewerbung ausschlie\u00dflich per E-Mail an <a href=\\\"mailto:job@nordisk-buero.com\\\">job@nordisk-buero.com<\/a><br \/>Betreff: Praktikum Grafikdesign Standort Frankfurt<\/p>\",\r\n      \"align\": \"top\",\r\n      \"row\": 0,\r\n      \"col\": 11,\r\n      \"colspan\": 9,\r\n      \"offsetx\": 0,\r\n      \"offsety\": 0,\r\n      \"spaceabove\": 0,\r\n      \"spacebelow\": 0,\r\n      \"yvel\": 1,\r\n      \"push\": 1,\r\n      \"relid\": 4,\r\n      \"absolute_position\": false\r\n    }\r\n  ]\r\n}","phonegrid":"","_links":{"self":[{"href":"https:\/\/nordisk-buero.com\/en\/wp-json\/wp\/v2\/posts\/439","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/nordisk-buero.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/nordisk-buero.com\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/nordisk-buero.com\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/nordisk-buero.com\/en\/wp-json\/wp\/v2\/comments?post=439"}],"version-history":[{"count":0,"href":"https:\/\/nordisk-buero.com\/en\/wp-json\/wp\/v2\/posts\/439\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/nordisk-buero.com\/en\/wp-json\/wp\/v2\/media\/1543"}],"wp:attachment":[{"href":"https:\/\/nordisk-buero.com\/en\/wp-json\/wp\/v2\/media?parent=439"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/nordisk-buero.com\/en\/wp-json\/wp\/v2\/categories?post=439"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/nordisk-buero.com\/en\/wp-json\/wp\/v2\/tags?post=439"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}